{"id":11282,"date":"2024-07-01T11:02:16","date_gmt":"2024-07-01T11:02:16","guid":{"rendered":"https:\/\/www.sensormedica.com\/?page_id=11282"},"modified":"2025-05-20T06:01:29","modified_gmt":"2025-05-20T06:01:29","slug":"cmef-2024","status":"publish","type":"page","link":"https:\/\/www.sensormedica.com\/it\/cmef-2024\/","title":{"rendered":"QCMV 2024"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-11282","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CMEF 2024 - Sensor Medica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sensormedica.com\/it\/cmef-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CMEF 2024 - Sensor Medica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sensormedica.com\/it\/cmef-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Sensor Medica\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T06:01:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sensormedica.com\\\/cmef-2024\\\/\",\"url\":\"https:\\\/\\\/www.sensormedica.com\\\/cmef-2024\\\/\",\"name\":\"CMEF 2024 - Sensor Medica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sensormedica.com\\\/#website\"},\"datePublished\":\"2024-07-01T11:02:16+00:00\",\"dateModified\":\"2025-05-20T06:01:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sensormedica.com\\\/cmef-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sensormedica.com\\\/cmef-2024\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sensormedica.com\\\/cmef-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sensormedica.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CMEF 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sensormedica.com\\\/#website\",\"url\":\"https:\\\/\\\/www.sensormedica.com\\\/\",\"name\":\"Sensor Medica\",\"description\":\"Technology in Motion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sensormedica.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CMEF 2024 - Sensor Medica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sensormedica.com\/it\/cmef-2024\/","og_locale":"it_IT","og_type":"article","og_title":"CMEF 2024 - Sensor Medica","og_url":"https:\/\/www.sensormedica.com\/it\/cmef-2024\/","og_site_name":"Sensor Medica","article_modified_time":"2025-05-20T06:01:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sensormedica.com\/cmef-2024\/","url":"https:\/\/www.sensormedica.com\/cmef-2024\/","name":"CMEF 2024 - Sensor Medica","isPartOf":{"@id":"https:\/\/www.sensormedica.com\/#website"},"datePublished":"2024-07-01T11:02:16+00:00","dateModified":"2025-05-20T06:01:29+00:00","breadcrumb":{"@id":"https:\/\/www.sensormedica.com\/cmef-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sensormedica.com\/cmef-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sensormedica.com\/cmef-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sensormedica.com\/"},{"@type":"ListItem","position":2,"name":"CMEF 2024"}]},{"@type":"WebSite","@id":"https:\/\/www.sensormedica.com\/#website","url":"https:\/\/www.sensormedica.com\/","name":"Sensor Medica","description":"Tecnologia in Movimento","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sensormedica.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/pages\/11282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/comments?post=11282"}],"version-history":[{"count":1,"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/pages\/11282\/revisions"}],"predecessor-version":[{"id":11283,"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/pages\/11282\/revisions\/11283"}],"wp:attachment":[{"href":"https:\/\/www.sensormedica.com\/it\/wp-json\/wp\/v2\/media?parent=11282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}